{"id":13321,"date":"2023-08-04T13:12:00","date_gmt":"2023-08-04T11:12:00","guid":{"rendered":"https:\/\/www.eures-andalucia-algarve.eu\/trabalhar-na-andaluzia\/"},"modified":"2023-11-23T12:18:10","modified_gmt":"2023-11-23T11:18:10","slug":"trabalhar-na-andaluzia","status":"publish","type":"page","link":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-na-andaluzia\/","title":{"rendered":"Trabalhar na Andaluzia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13321\" class=\"elementor elementor-13321 elementor-2654\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8505632 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"8505632\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6396f5f\" data-id=\"6396f5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d64846 elementor-align-left elementor-widget elementor-widget-bdevs-page-header\" data-id=\"8d64846\" data-element_type=\"widget\" data-widget_type=\"bdevs-page-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"full-landing-image sx-bnr-inr overlay-wraper  bg-top-center\"    style=\"background-image:url(https:\/\/www.eures-andalucia-algarve.eu\/wp-content\/uploads\/2023\/10\/cabgenerico-V2-6-1.jpg);\">\r\n            <div class=\"overlay-main bg-white opacity-0\"><\/div>\r\n            <div class=\"container\">\r\n                <div class=\"sx-bnr-inr-entry\">\r\n                    <div class=\"banner-title-outer\">\r\n                                                <div class=\"banner-title-name\">\r\n                                                        <span class=\"sx-bnr-sm-title\">Informa\u00e7\u00f5es para as pessoas que vivem no Algarve e trabalham ou procuram trabalho na Andaluzia<\/span>\r\n                                                                                    <h2 class=\"sx-title\">Vivo no Algarve e trabalho na Andaluzia<\/h2>\r\n                                                    <\/div>\r\n                                                <!-- BREADCRUMB ROW -->                            \r\n                        <div>\r\n                            <ul class=\"sx-breadcrumb breadcrumb-style-2\">\r\n                                                                <li><a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/\">Trabajadores<\/a><\/li>\r\n                                                                                                <li>Trabajar en Andaluc\u00eda<\/li>\r\n                                                            <\/ul>\r\n                        <\/div>\r\n                        <!-- BREADCRUMB ROW END -->  \r\n                    <\/div>                          \r\n                <\/div>\r\n            <\/div> \r\n                        <div class=\"sx-bnr-outline-text\">\r\n                <h1>Oficina OESTE<\/h1>\r\n            <\/div> \r\n                    <\/div>\r\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04abc4b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"04abc4b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cb8f3b\" data-id=\"5cb8f3b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7454369 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"7454369\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7f71485\" data-id=\"7f71485\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1630b7 elementor-widget elementor-widget-heading\" data-id=\"c1630b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h5 class=\"elementor-heading-title elementor-size-default\">\nCONDI\u00c7\u00d5ES E OPORTUNIDADES DE CARREIRA<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fc71c2 elementor-widget elementor-widget-heading\" data-id=\"8fc71c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Informa\u00e7\u00f5es para os trabalhadores\/residentes que pretendam trabalhar na regi\u00e3o da Andaluzia<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c9b7b73\" data-id=\"c9b7b73\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0f9ef77 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0f9ef77\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-895be94 elementor-invisible\" data-id=\"895be94\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6537ed elementor-view-stacked elementor-shape-square elementor-position-left elementor-mobile-position-left elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"e6537ed\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/?page_id=13354\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-link\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/?page_id=13354\" >\n\t\t\t\t\t\t<h3>Vivo no Algarve e trabalho na Andaluzia.<\/h3>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<ul>\n<li><strong>Condi\u00e7\u00f5es de trabalho\nna Andaluzia<\/strong><\/li>\n\n<ul>\n<li>Seguran\u00e7a social para os trabalhadores transfronteiri\u00e7os  <\/li>\n<li>Legisla\u00e7\u00e3o laboral em Espanha<\/li>\n<li>Cuidados de sa\u00fade na Andaluzia<\/li>\n<li>Tributa\u00e7\u00e3o dos trabalhadores transfronteiri\u00e7os portugueses<\/li>\n<\/ul>\n<br>\n<li><strong>Condi\u00e7\u00f5es de vida na Andaluzia<\/strong><\/li>\n\n<ul>\n<li>Habita\u00e7\u00e3o<\/li>\n<li>Educa\u00e7\u00e3o<\/li>\n<li>Autoriza\u00e7\u00f5es<\/li>\n<li>Ve\u00edculo<\/li>\n<li>T\u00edtulos<\/li>\n<\/ul>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7512b9 elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"f7512b9\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/vivo-no-algarve-e-trabalho-na-andaluzia\/\" data-text=\"Ler mais\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"lnr lnr-link\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Acesso \u00e0 informa\u00e7\u00e3o<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9e85df2 elementor-invisible\" data-id=\"9e85df2\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-973b9fd elementor-view-stacked elementor-shape-square elementor-position-left elementor-mobile-position-left elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"973b9fd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/vivo-no-algarve-e-estou-a-procura-de-um-emprego-na-andaluzia\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-link\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/vivo-no-algarve-e-estou-a-procura-de-um-emprego-na-andaluzia\/\" >\n\t\t\t\t\t\t<h3>Vivo no Algarve e estou \u00e0 procura de um emprego na Andaluzia.<\/h3>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<ul>\n<li>Situa\u00e7\u00e3o do mercado\nMercado de trabalho andaluz<\/li>\n<li>Onde houver bancas\ndispon\u00edvel<\/li>\n<li>Como apresentar o meu\ncandidatura?<\/li>\n<\/ul>\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46d6895 elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"46d6895\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/vivo-no-algarve-e-estou-a-procura-de-um-emprego-na-andaluzia\/\" data-text=\"Ler mais\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"lnr lnr-link\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Acesso \u00e0 informa\u00e7\u00e3o<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8816d80 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"8816d80\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ee13b3 elementor-invisible\" data-id=\"5ee13b3\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce88bc5 elementor-widget elementor-widget-wpr-elementor-template\" data-id=\"ce88bc5\" data-element_type=\"widget\" data-widget_type=\"wpr-elementor-template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9257\" class=\"elementor elementor-9257\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f20eb6e elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"7f20eb6e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-7be64c28 elementor-invisible\" data-id=\"7be64c28\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-3206bfa6\" data-id=\"3206bfa6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a7c668c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2a7c668c\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3874ac69 elementor-invisible\" data-id=\"3874ac69\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2361bd7e elementor-widget elementor-widget-heading\" data-id=\"2361bd7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pide cita personalizada con tu consejer@ transfronterizo\n\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13e66b2d elementor-widget elementor-widget-text-editor\" data-id=\"13e66b2d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Puedes pedir atenci\u00f3n personalizada a trav\u00e9s de nuestra web, y si es necesario concertar una cita con un agente transfronterizo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fc2c4a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3fc2c4a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/oficina-oeste\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar atenci\u00f3n personalizada<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-4584befb elementor-invisible\" data-id=\"4584befb\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<span class=\"wpr-template-edit-btn\" data-permalink=\"https:\/\/www.eures-andalucia-algarve.eu\/?elementor_library=banner-pide-cita-personalizada\">Edit Template<\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d255ff elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0d255ff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-bcc4083 elementor-invisible\" data-id=\"bcc4083\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-191c195\" data-id=\"191c195\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06b2b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"06b2b74\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-043b675 elementor-invisible\" data-id=\"043b675\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfbfc5f elementor-widget elementor-widget-heading\" data-id=\"bfbfc5f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Marque uma reuni\u00e3o personalizada com o seu consultor transfronteiri\u00e7o\n\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e423c6b elementor-widget elementor-widget-text-editor\" data-id=\"e423c6b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Pode solicitar uma aten\u00e7\u00e3o personalizada atrav\u00e9s do nosso s\u00edtio Web e, se necess\u00e1rio, marcar uma reuni\u00e3o com um agente transfronteiri\u00e7o.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2bc39d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b2bc39d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/gabinete-west\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Pedir uma aten\u00e7\u00e3o personalizada<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-49317e3 elementor-invisible\" data-id=\"49317e3\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-514e185 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"514e185\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03df857\" data-id=\"03df857\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7805845 banners elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"7805845\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-622c1c3 elementor-invisible\" data-id=\"622c1c3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-530e5c9 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"530e5c9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-no-algarve\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-management\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-no-algarve\/\" >\n\t\t\t\t\t\tVivo na Andaluzia e trabalho no Algarve\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInforma\u00e7\u00f5es para as pessoas que vivem na Andaluzia e trabalham ou procuram trabalho no Algarve\n<!-- Busco empleo en Andaluc\u00eda.<br>\nBusco empleo en Portugal.<br> \u00bfQui\u00e9n puede atenderme?\n<span style=\"font-size:0.65em;text-transform:uppercase;font-weight:600;px;background:#0F4BB9;color:#fff; padding:8px 8px;border-radius:3px;margin:10px 0;display:inline-block\">Contacta con la oficina OESTE<\/span>\n-->\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee83f3b elementor-align-right elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"ee83f3b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactar o Oficina OESTE<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-552b19d elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"552b19d\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-no-algarve\/\" data-text=\"Balc\u00e3o \u00fanico digital\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\" ti-new-window\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Aceder ao Oficina OESTE<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dfca7cc elementor-invisible\" data-id=\"dfca7cc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07275b1 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"07275b1\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-na-andaluzia\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-management\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-na-andaluzia\/\" >\n\t\t\t\t\t\tVivo no Algarve e trabalho na Andaluzia\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInforma\u00e7\u00f5es para as pessoas que vivem no Algarve e trabalham ou procuram trabalho na Andaluzia\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb5b9e elementor-align-right elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"2eb5b9e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-na-andaluzia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactar o Oficina OESTE<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9639c57 elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"9639c57\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/trabalhar-na-andaluzia\/\" data-text=\"Balc\u00e3o \u00fanico digital\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\" ti-new-window\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Aceder ao Oficina OESTE<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1960254 elementor-invisible\" data-id=\"1960254\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac5d704 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"ac5d704\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/ofertas-de-emprego-na-fronteira\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-hand_shake\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/ofertas-de-emprego-na-fronteira\/\" >\n\t\t\t\t\t\tPesquisa de ofertas de emprego na fronteira\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDescubra as ofertas de emprego mais interessantes na fronteira Andaluzia\/Algarve.\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-508fdfc elementor-align-right elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"508fdfc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactar o Oficina OESTE<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-290351a elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"290351a\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/ofertas-de-emprego-na-fronteira\/\" data-text=\"Quadro de empregos na fronteira\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\" ti-new-window\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Acesso a ofertas de emprego<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-beed238 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"beed238\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-55df738\" data-id=\"55df738\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-655ff11 elementor-widget elementor-widget-heading\" data-id=\"655ff11\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">OFICINA ESPECIALIZADA EM SERVI\u00c7OS DE EMPREGO TRANSFRONTEIRI\u00c7OS<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0435ca6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0435ca6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OESTE<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-097806d elementor-widget elementor-widget-text-editor\" data-id=\"097806d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div style=\"max-width:600px;margin:0 auto;text-align:center\">Todas as informa\u00e7\u00f5es necess\u00e1rias para que trabalhar ou procurar trabalhadores no seu pa\u00eds vizinho seja t\u00e3o f\u00e1cil como no seu pr\u00f3prio pa\u00eds.<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ca9900 banners elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0ca9900\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9fa1ff3 elementor-invisible\" data-id=\"9fa1ff3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-392dcd5 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"392dcd5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/empresas-andaluzas\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\" icon_toolbox_alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/empresas-andaluzas\/\" >\n\t\t\t\t\t\tEmpresas da Andaluzia\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInforma\u00e7\u00e3o para as empresas andaluzas que t\u00eam ou procuram trabalhadores no Algarve\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b86127 elementor-align-right elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"9b86127\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactar o Oficina OESTE<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dab03d elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"4dab03d\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/empresas-andaluzas\/\" data-text=\"Balc\u00e3o \u00fanico digital\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\" ti-new-window\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Aceder ao Oficina OESTE<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ebbf8c7 elementor-invisible\" data-id=\"ebbf8c7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3310732 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"3310732\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/empresas-no-algarve\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\" icon_toolbox_alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/empresas-no-algarve\/\" >\n\t\t\t\t\t\tEmpresas no Algarve\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInforma\u00e7\u00e3o para empresas algarvias com ou \u00e0 procura de trabalhadores na Andaluzia\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-999f068 elementor-align-right elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"999f068\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactar o Oficina OESTE<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e6ac84 elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"8e6ac84\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/empresas-no-algarve\/\" data-text=\"Balc\u00e3o \u00fanico digital\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\" ti-new-window\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Aceder ao Oficina OESTE<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c45225a elementor-invisible\" data-id=\"c45225a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15cdf4b elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"15cdf4b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/publicacao-de-anuncios-de-emprego-transfronteiricos\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-bullhorn\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/publicacao-de-anuncios-de-emprego-transfronteiricos\/\" >\n\t\t\t\t\t\tPublicar ofertas de emprego na fronteira\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDivulgue as suas ofertas de emprego na regi\u00e3o vizinha\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e06f0 elementor-align-right elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"56e06f0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactar o Oficina OESTE<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b49551e elementor-widget__width-initial elementor-widget elementor-widget-eael-creative-button\" data-id=\"b49551e\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--rayen\" href=\"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/publicacao-de-anuncios-de-emprego-transfronteiricos\/\" data-text=\"Publique aqui a sua oferta de emprego\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\" ti-new-window\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Publique aqui a sua oferta de emprego<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6e56277 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"6e56277\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b495bad elementor-widget elementor-widget-shortcode\" data-id=\"b495bad\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4987\" class=\"elementor elementor-4987\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ed4a0d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1ed4a0d2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17c52543\" data-id=\"17c52543\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54b84c86 banners elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"54b84c86\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53e57b73 elementor-invisible\" data-id=\"53e57b73\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-097ac95 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"097ac95\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/trabajar-en-el-algarve\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-management\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/trabajar-en-el-algarve\/\" >\n\t\t\t\t\t\tVivo en Andaluc\u00eda y trabajo en el Algarve\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInformaci\u00f3n para personas residentes en Andaluc\u00eda y que trabajan o buscan trabajo en el Algarve\n<!--\n\nBusco empleo en Andaluc\u00eda.<br>\nBusco empleo en Portugal.<br> \u00bfQui\u00e9n puede atenderme?\n<span style=\"font-size:0.65em;text-transform:uppercase;font-weight:600;px;background:#0F4BB9;color:#fff; padding:8px 8px;border-radius:3px;margin:10px 0;display:inline-block\">Contacta con la oficina OESTE<\/span>\n-->\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4cee7244 elementor-invisible\" data-id=\"4cee7244\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f439c9 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"1f439c9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/trabajar-en-andalucia\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-management\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/trabajar-en-andalucia\/\" >\n\t\t\t\t\t\tVivo en el Algarve y trabajo en Andaluc\u00eda\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInformaci\u00f3n para personas residentes en el Algarve y que trabajan o buscan trabajo en Andaluc\u00eda\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-97009d3 elementor-invisible\" data-id=\"97009d3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d14a523 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"d14a523\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/anuncios-de-empleo-fronterizo\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-hand_shake\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/anuncios-de-empleo-fronterizo\/\" >\n\t\t\t\t\t\tBuscar ofertas de empleo fronterizo\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tConoce las ofertas de empleo m\u00e1s interesantes de la frontera Andaluc\u00eda\/Algarve\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6824d2b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"6824d2b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-25de82d8\" data-id=\"25de82d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79305019 elementor-widget elementor-widget-heading\" data-id=\"79305019\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">OFICINA ESPECIALIZADA EN SERVICIOS TRANSFRONTERIZOS DE EMPLEO<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72866ec0 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"72866ec0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OESTE<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1134a845 elementor-widget elementor-widget-text-editor\" data-id=\"1134a845\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div style=\"max-width:600px;margin:0 auto;text-align:center\">Toda la informaci\u00f3n necesaria para que trabajar o buscar trabajadores en el pa\u00eds vecino sea tan sencillo como hacerlo en tu propio pa\u00eds<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cb86ae5 banners elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"cb86ae5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c323184 elementor-invisible\" data-id=\"c323184\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c944662 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"c944662\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/empresas-de-andalucia\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\" icon_toolbox_alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/empresas-de-andalucia\/\" >\n\t\t\t\t\t\tEmpresas Andaluzas\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInformaci\u00f3n para empresas andaluzas que tienen o buscan trabajadores en el Algarve\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-74d8a20 elementor-invisible\" data-id=\"74d8a20\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be268d8 elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"be268d8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/empresas-del-algarve\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\" icon_toolbox_alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/empresas-del-algarve\/\" >\n\t\t\t\t\t\tEmpresas del Algarve\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInformaci\u00f3n para empresas del Algarve que tienen o buscan trabajadores en Andaluc\u00eda\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c66637e elementor-invisible\" data-id=\"c66637e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f990fe elementor-position-left elementor-mobile-position-left elementor-view-stacked elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"8f990fe\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/publicar-anuncios-de-empleo-transfronterizo\/\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-bullhorn\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.eures-andalucia-algarve.eu\/publicar-anuncios-de-empleo-transfronterizo\/\" >\n\t\t\t\t\t\tPublicar ofertas de empleo fronterizo\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDivulga tus ofertas de empleo en la regi\u00f3n vecina\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<span class=\"wpr-template-edit-btn\" data-permalink=\"https:\/\/www.eures-andalucia-algarve.eu\/?elementor_library=acceso-oficina-oeste-bg-azul\">Edit Template<\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb6b8ee elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"bb6b8ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6676683\" data-id=\"6676683\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a24486 elementor-widget elementor-widget-shortcode\" data-id=\"3a24486\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8664\" class=\"elementor elementor-8664\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-339e507 encuestas elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"339e507\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-294991ae\" data-id=\"294991ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dce98f7 elementor-widget elementor-widget-html\" data-id=\"dce98f7\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='bootstrap-yop yop-poll-mc'>\n\t\t\t\t\t\t\t<div class=\"yop-poll-container\" data-id=\"1\" data-ajax=\"1\" data-tid=\"\" data-pid=\"13321\" data-show-results-only=\"false\"><\/div>\n\t\t\t\t\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<span class=\"wpr-template-edit-btn\" data-permalink=\"https:\/\/www.eures-andalucia-algarve.eu\/?elementor_library=encuesta-informacion-util\">Edit Template<\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56307f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"56307f0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-718bef8\" data-id=\"718bef8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00f5es para as pessoas que vivem no Algarve e trabalham ou procuram trabalho na Andaluzia Vivo no Algarve e trabalho na Andaluzia Trabajadores Trabajar en Andaluc\u00eda Oficina OESTE CONDI\u00c7\u00d5ES E OPORTUNIDADES DE CARREIRA Informa\u00e7\u00f5es para os trabalhadores\/residentes que pretendam trabalhar na regi\u00e3o da Andaluzia Vivo no Algarve e trabalho na Andaluzia. Condi\u00e7\u00f5es de trabalho na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/home-1.php","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"cybocfi_hide_featured_image":"","footnotes":"","_links_to":"","_links_to_target":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/pages\/13321"}],"collection":[{"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/comments?post=13321"}],"version-history":[{"count":16,"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/pages\/13321\/revisions"}],"predecessor-version":[{"id":15528,"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/pages\/13321\/revisions\/15528"}],"wp:attachment":[{"href":"https:\/\/www.eures-andalucia-algarve.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=13321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}